{"id":19935,"date":"2024-11-27T13:08:52","date_gmt":"2024-11-27T17:08:52","guid":{"rendered":"https:\/\/caid.gob.do\/caid\/?p=19935"},"modified":"2024-12-02T11:31:17","modified_gmt":"2024-12-02T15:31:17","slug":"el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos","status":"publish","type":"post","link":"https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/","title":{"rendered":"El CAID presenta sus avances institucionales de los \u00faltimos tres a\u00f1os"},"content":{"rendered":"\n<p><em>\u00abUna sociedad inclusiva, que no deje a nadie atr\u00e1s, es un compromiso irrenunciable del CAID\u00bb, afirm\u00f3 el padre Hern\u00e1ndez D\u00edaz.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/caid.gob.do\/caid\/wp-content\/uploads\/El-CAID-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos-nota-de-prensa.jpeg\" alt=\"\" class=\"wp-image-19936\"\/><\/figure>\n\n\n\n<p>La redefinici\u00f3n del modelo de atenci\u00f3n para ampliar la cobertura, el acortamiento de los tiempos de respuesta a las familias solicitantes y la optimizaci\u00f3n de los servicios terap\u00e9uticos, son citados entre los logros alcanzados por el Centro de Atenci\u00f3n Integral para la Discapacidad (CAID) durante sus \u00faltimos tres a\u00f1os gesti\u00f3n.<\/p>\n\n\n\n<p>Los datos est\u00e1n contenidos en la memoria 2021-2024 puesta a circular este mi\u00e9rcoles por la instituci\u00f3n que presta servicios a ni\u00f1os y ni\u00f1as con s\u00edndrome de Down, trastornos del espectro autista y par\u00e1lisis cerebral.<\/p>\n\n\n\n<p>Se cita como un hito el inicio de la ejecuci\u00f3n del Plan Nacional de Unidades de Intervenci\u00f3n Terap\u00e9utica Territorial (UITT), que acerca los servicios a las comunidades mediante unidades de atenci\u00f3n instaladas en sus demarcaciones y reduce el tiempo de permanencia de los usuarios, permitiendo una mayor posibilidad de acoger a nuevos solicitantes.<\/p>\n\n\n\n<p>\u00abDurante cada d\u00eda de estos tres a\u00f1os, el personal m\u00e9dico, terap\u00e9utico, t\u00e9cnico y administrativo ha dado lo mejor de s\u00ed para lograr que el CAID cumpliera, y siga haci\u00e9ndolo en el futuro, con sus prop\u00f3sitos y compromisos misionales: potenciar el desarrollo de las habilidades de ni\u00f1os y ni\u00f1as con discapacidad, a trav\u00e9s de un servicio de atenci\u00f3n integral\u00bb, afirm\u00f3 el padre Jorge William Hern\u00e1ndez D\u00edaz, presidente del Consejo Directivo de la instituci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"6000\" height=\"3376\" src=\"https:\/\/caid.gob.do\/caid\/wp-content\/uploads\/EVENTO-MEMORIAS-GESTION-2024-FOTOS-DSC08262.jpg\" alt=\"\" class=\"wp-image-19948\"\/><\/figure>\n\n\n\n<p>Entre los logros m\u00e1s significativos, el CAID destaca la reducci\u00f3n de la lista para iniciar los planes terap\u00e9uticos en toda la red del CAID, conformada por sus sedes en Santo Domingo Oeste, Santo Domingo Este, Santiago y San Juan de la Maguana. Los esfuerzos en este sentido han permitido pasar de 1,719 usuarios y familias en per\u00edodo 2016-2019 a 3,920 durante el \u00faltimo trienio.<\/p>\n\n\n\n<p>De manera simult\u00e1nea a los cambios organizativos y la adopci\u00f3n de un nuevo modelo de atenci\u00f3n, el CAID ha desarrollado una campa\u00f1a ininterrumpida para crear conciencia sobre la discapacidad y garantizar que los derechos de los ni\u00f1os, ni\u00f1as, adolescentes y adultos con alguna condici\u00f3n tengan plena vigencia.<\/p>\n\n\n\n<p>Al acto de presentaci\u00f3n de la memoria, celebrado en la sede de Santo Domingo Oeste, asistieron asociaciones sin fines de lucro que trabajan con la discapacidad, autoridades, funcionarios y personalidades de la sociedad civil.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/caid.gob.do\/caid\/inicio\/sobre-nosotros\/memorias-de-gestion\/\">Accede a nuestra Memoria de Gesti\u00f3n dando clic aqu\u00ed<\/a><\/strong><\/p>\n\n\n\n<STYLE>\n.wp-image-19936{ WIDTH: 100%}\n.wp-image-19948 {width:100%}<\/STYLE>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La redefinici\u00f3n del modelo de atenci\u00f3n para ampliar la cobertura, el acortamiento de los tiempos de respuesta a las familias solicitantes y la optimizaci\u00f3n de los servicios terap\u00e9uticos, son citados entre los logros alcanzados por el Centro de Atenci\u00f3n Integral para la Discapacidad (CAID) durante sus \u00faltimos tres a\u00f1os gesti\u00f3n.<\/p>\n","protected":false},"author":1,"featured_media":19936,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[50],"class_list":["post-19935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-santo-domingo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>El CAID presenta sus avances institucionales de los \u00faltimos tres a\u00f1os - CAID<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"El CAID presenta sus avances institucionales de los \u00faltimos tres a\u00f1os - CAID\" \/>\r\n<meta property=\"og:description\" content=\"La redefinici\u00f3n del modelo de atenci\u00f3n para ampliar la cobertura, el acortamiento de los tiempos de respuesta a las familias solicitantes y la optimizaci\u00f3n de los servicios terap\u00e9uticos, son citados entre los logros alcanzados por el Centro de Atenci\u00f3n Integral para la Discapacidad (CAID) durante sus \u00faltimos tres a\u00f1os gesti\u00f3n.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/\" \/>\r\n<meta property=\"og:site_name\" content=\"CAID\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redcaidrd\" \/>\r\n<meta property=\"article:published_time\" content=\"2024-11-27T17:08:52+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-12-02T15:31:17+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/caid.gob.do\/caid\/wp-content\/uploads\/El-CAID-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos-nota-de-prensa.jpeg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\r\n\t<meta property=\"og:image:height\" content=\"900\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"j.ortega\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@CAIDRDO\" \/>\r\n<meta name=\"twitter:site\" content=\"@CAIDRDO\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"j.ortega\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\\\/\"},\"author\":{\"name\":\"j.ortega\",\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/#\\\/schema\\\/person\\\/eabe18a8e75d76804c0ab7a18828fb37\"},\"headline\":\"El CAID presenta sus avances institucionales de los \u00faltimos tres a\u00f1os\",\"datePublished\":\"2024-11-27T17:08:52+00:00\",\"dateModified\":\"2024-12-02T15:31:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\\\/\"},\"wordCount\":441,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/wp-content\\\/uploads\\\/El-CAID-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos-nota-de-prensa.jpeg\",\"keywords\":[\"Santo Domingo\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/caid.gob.do\\\/caid\\\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\\\/\",\"url\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\\\/\",\"name\":\"El CAID presenta sus avances institucionales de los \u00faltimos tres a\u00f1os - CAID\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/wp-content\\\/uploads\\\/El-CAID-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos-nota-de-prensa.jpeg\",\"datePublished\":\"2024-11-27T17:08:52+00:00\",\"dateModified\":\"2024-12-02T15:31:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/caid.gob.do\\\/caid\\\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/wp-content\\\/uploads\\\/El-CAID-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos-nota-de-prensa.jpeg\",\"contentUrl\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/wp-content\\\/uploads\\\/El-CAID-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos-nota-de-prensa.jpeg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Est\u00e1s aqu\u00ed:\",\"item\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El CAID presenta sus avances institucionales de los \u00faltimos tres a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/#website\",\"url\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/\",\"name\":\"CAID\",\"description\":\"Centro de Atenci\u00f3n Integral a la Discapacidad\",\"publisher\":{\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/#organization\",\"name\":\"Centro de Atenci\u00f3n Integral para la Discapacidad\",\"url\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/wp-content\\\/uploads\\\/CAID-LOGOS-EN-PNG_Mesa-de-trabajo-1-2-1024x505-1.png\",\"contentUrl\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/wp-content\\\/uploads\\\/CAID-LOGOS-EN-PNG_Mesa-de-trabajo-1-2-1024x505-1.png\",\"width\":1024,\"height\":505,\"caption\":\"Centro de Atenci\u00f3n Integral para la Discapacidad\"},\"image\":{\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redcaidrd\",\"https:\\\/\\\/x.com\\\/CAIDRDO\",\"https:\\\/\\\/www.instagram.com\\\/caidrd\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCLnt-fnRlxQdgJQwjgWkrCg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/#\\\/schema\\\/person\\\/eabe18a8e75d76804c0ab7a18828fb37\",\"name\":\"j.ortega\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/375f8cefc66fc63362d75424f6f727ddbbecd8c33b29ce1234841e4c4c30563f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/375f8cefc66fc63362d75424f6f727ddbbecd8c33b29ce1234841e4c4c30563f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/375f8cefc66fc63362d75424f6f727ddbbecd8c33b29ce1234841e4c4c30563f?s=96&d=mm&r=g\",\"caption\":\"j.ortega\"},\"sameAs\":[\"https:\\\/\\\/caid.gob.do\\\/caid\"],\"url\":\"https:\\\/\\\/caid.gob.do\\\/caid\\\/author\\\/j-ortega\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El CAID presenta sus avances institucionales de los \u00faltimos tres a\u00f1os - CAID","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/","og_locale":"es_ES","og_type":"article","og_title":"El CAID presenta sus avances institucionales de los \u00faltimos tres a\u00f1os - CAID","og_description":"La redefinici\u00f3n del modelo de atenci\u00f3n para ampliar la cobertura, el acortamiento de los tiempos de respuesta a las familias solicitantes y la optimizaci\u00f3n de los servicios terap\u00e9uticos, son citados entre los logros alcanzados por el Centro de Atenci\u00f3n Integral para la Discapacidad (CAID) durante sus \u00faltimos tres a\u00f1os gesti\u00f3n.","og_url":"https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/","og_site_name":"CAID","article_publisher":"https:\/\/www.facebook.com\/redcaidrd","article_published_time":"2024-11-27T17:08:52+00:00","article_modified_time":"2024-12-02T15:31:17+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/caid.gob.do\/caid\/wp-content\/uploads\/El-CAID-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos-nota-de-prensa.jpeg","type":"image\/jpeg"}],"author":"j.ortega","twitter_card":"summary_large_image","twitter_creator":"@CAIDRDO","twitter_site":"@CAIDRDO","twitter_misc":{"Written by":"j.ortega","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/#article","isPartOf":{"@id":"https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/"},"author":{"name":"j.ortega","@id":"https:\/\/caid.gob.do\/caid\/#\/schema\/person\/eabe18a8e75d76804c0ab7a18828fb37"},"headline":"El CAID presenta sus avances institucionales de los \u00faltimos tres a\u00f1os","datePublished":"2024-11-27T17:08:52+00:00","dateModified":"2024-12-02T15:31:17+00:00","mainEntityOfPage":{"@id":"https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/"},"wordCount":441,"commentCount":0,"publisher":{"@id":"https:\/\/caid.gob.do\/caid\/#organization"},"image":{"@id":"https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/caid.gob.do\/caid\/wp-content\/uploads\/El-CAID-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos-nota-de-prensa.jpeg","keywords":["Santo Domingo"],"articleSection":["Noticias"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/","url":"https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/","name":"El CAID presenta sus avances institucionales de los \u00faltimos tres a\u00f1os - CAID","isPartOf":{"@id":"https:\/\/caid.gob.do\/caid\/#website"},"primaryImageOfPage":{"@id":"https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/#primaryimage"},"image":{"@id":"https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/caid.gob.do\/caid\/wp-content\/uploads\/El-CAID-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos-nota-de-prensa.jpeg","datePublished":"2024-11-27T17:08:52+00:00","dateModified":"2024-12-02T15:31:17+00:00","breadcrumb":{"@id":"https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/#primaryimage","url":"https:\/\/caid.gob.do\/caid\/wp-content\/uploads\/El-CAID-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos-nota-de-prensa.jpeg","contentUrl":"https:\/\/caid.gob.do\/caid\/wp-content\/uploads\/El-CAID-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos-nota-de-prensa.jpeg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/caid.gob.do\/caid\/el-caid-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Est\u00e1s aqu\u00ed:","item":"https:\/\/caid.gob.do\/caid\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/caid.gob.do\/caid\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"El CAID presenta sus avances institucionales de los \u00faltimos tres a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/caid.gob.do\/caid\/#website","url":"https:\/\/caid.gob.do\/caid\/","name":"CAID","description":"Centro de Atenci\u00f3n Integral a la Discapacidad","publisher":{"@id":"https:\/\/caid.gob.do\/caid\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/caid.gob.do\/caid\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/caid.gob.do\/caid\/#organization","name":"Centro de Atenci\u00f3n Integral para la Discapacidad","url":"https:\/\/caid.gob.do\/caid\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/caid.gob.do\/caid\/#\/schema\/logo\/image\/","url":"https:\/\/caid.gob.do\/caid\/wp-content\/uploads\/CAID-LOGOS-EN-PNG_Mesa-de-trabajo-1-2-1024x505-1.png","contentUrl":"https:\/\/caid.gob.do\/caid\/wp-content\/uploads\/CAID-LOGOS-EN-PNG_Mesa-de-trabajo-1-2-1024x505-1.png","width":1024,"height":505,"caption":"Centro de Atenci\u00f3n Integral para la Discapacidad"},"image":{"@id":"https:\/\/caid.gob.do\/caid\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redcaidrd","https:\/\/x.com\/CAIDRDO","https:\/\/www.instagram.com\/caidrd\/","https:\/\/www.youtube.com\/channel\/UCLnt-fnRlxQdgJQwjgWkrCg"]},{"@type":"Person","@id":"https:\/\/caid.gob.do\/caid\/#\/schema\/person\/eabe18a8e75d76804c0ab7a18828fb37","name":"j.ortega","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/secure.gravatar.com\/avatar\/375f8cefc66fc63362d75424f6f727ddbbecd8c33b29ce1234841e4c4c30563f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/375f8cefc66fc63362d75424f6f727ddbbecd8c33b29ce1234841e4c4c30563f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/375f8cefc66fc63362d75424f6f727ddbbecd8c33b29ce1234841e4c4c30563f?s=96&d=mm&r=g","caption":"j.ortega"},"sameAs":["https:\/\/caid.gob.do\/caid"],"url":"https:\/\/caid.gob.do\/caid\/author\/j-ortega\/"}]}},"jetpack_featured_media_url":"https:\/\/caid.gob.do\/caid\/wp-content\/uploads\/El-CAID-presenta-sus-avances-institucionales-de-los-ultimos-tres-anos-nota-de-prensa.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/caid.gob.do\/caid\/wp-json\/wp\/v2\/posts\/19935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/caid.gob.do\/caid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/caid.gob.do\/caid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/caid.gob.do\/caid\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/caid.gob.do\/caid\/wp-json\/wp\/v2\/comments?post=19935"}],"version-history":[{"count":6,"href":"https:\/\/caid.gob.do\/caid\/wp-json\/wp\/v2\/posts\/19935\/revisions"}],"predecessor-version":[{"id":19986,"href":"https:\/\/caid.gob.do\/caid\/wp-json\/wp\/v2\/posts\/19935\/revisions\/19986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/caid.gob.do\/caid\/wp-json\/wp\/v2\/media\/19936"}],"wp:attachment":[{"href":"https:\/\/caid.gob.do\/caid\/wp-json\/wp\/v2\/media?parent=19935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/caid.gob.do\/caid\/wp-json\/wp\/v2\/categories?post=19935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/caid.gob.do\/caid\/wp-json\/wp\/v2\/tags?post=19935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}